{"id":1341,"count":1,"description":"","link":"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/","name":"Medio-Oriente","slug":"medio-oriente-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Medio-Oriente archivos<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medio-Oriente archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Todo Alfalfa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.todoalfalfa.com.ar\/noticias\/wp-content\/uploads\/2021\/01\/todo-alfalfa-captura-facebook.jpg?fit=1024%2C576&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/\",\"url\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/\",\"name\":\"Medio-Oriente archivos\",\"isPartOf\":{\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Principal\",\"item\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medio-Oriente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/#website\",\"url\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/\",\"name\":\"Todo Alfalfa\",\"description\":\"Web informativa de la cadena de la alfalfa argentina\",\"publisher\":{\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/#organization\",\"name\":\"Todo Alfalfa\",\"url\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-content\/uploads\/2020\/09\/logo-todo-alfalfa-modificado.png\",\"contentUrl\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-content\/uploads\/2020\/09\/logo-todo-alfalfa-modificado.png\",\"width\":350,\"height\":100,\"caption\":\"Todo Alfalfa\"},\"image\":{\"@id\":\"https:\/\/www.todoalfalfa.com.ar\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/todoalfalfa\",\"https:\/\/www.instagram.com\/todoalfalfa\",\"https:\/\/www.youtube.com\/@TodoAlfalfa\",\"https:\/\/www.linkedin.com\/company\/todoalfalfa\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medio-Oriente archivos","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Medio-Oriente archivos","og_url":"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/","og_site_name":"Todo Alfalfa","og_image":[{"width":1024,"height":576,"url":"https:\/\/i0.wp.com\/www.todoalfalfa.com.ar\/noticias\/wp-content\/uploads\/2021\/01\/todo-alfalfa-captura-facebook.jpg?fit=1024%2C576&ssl=1","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/","url":"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/","name":"Medio-Oriente archivos","isPartOf":{"@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/etiqueta\/medio-oriente-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Principal","item":"https:\/\/www.todoalfalfa.com.ar\/noticias\/"},{"@type":"ListItem","position":2,"name":"Medio-Oriente"}]},{"@type":"WebSite","@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/#website","url":"https:\/\/www.todoalfalfa.com.ar\/noticias\/","name":"Todo Alfalfa","description":"Web informativa de la cadena de la alfalfa argentina","publisher":{"@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.todoalfalfa.com.ar\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/#organization","name":"Todo Alfalfa","url":"https:\/\/www.todoalfalfa.com.ar\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-content\/uploads\/2020\/09\/logo-todo-alfalfa-modificado.png","contentUrl":"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-content\/uploads\/2020\/09\/logo-todo-alfalfa-modificado.png","width":350,"height":100,"caption":"Todo Alfalfa"},"image":{"@id":"https:\/\/www.todoalfalfa.com.ar\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/todoalfalfa","https:\/\/www.instagram.com\/todoalfalfa","https:\/\/www.youtube.com\/@TodoAlfalfa","https:\/\/www.linkedin.com\/company\/todoalfalfa\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-json\/wp\/v2\/tags\/1341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.todoalfalfa.com.ar\/noticias\/wp-json\/wp\/v2\/posts?tags=1341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}